{"id":97415,"date":"2002-10-01T00:01:31","date_gmt":"2002-09-30T22:01:31","guid":{"rendered":"http:\/\/www.editiondaslabor.de\/blog\/?p=97415"},"modified":"2022-01-01T06:17:19","modified_gmt":"2022-01-01T05:17:19","slug":"alte-katze","status":"publish","type":"post","link":"http:\/\/www.editiondaslabor.de\/blog\/2002\/10\/01\/alte-katze\/","title":{"rendered":"Alte Katze"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Katzenliteratur ist ihr ein Begriff.<\/p>\n<p>Gleich nach Grenz\u00f6ffnung suchte sie<\/p>\n<p>die esoterischen Teestuben auf<\/p>\n<p>kaufte wenig<\/p>\n<p>aber h\u00f6rte gern die Vogelstimmen<\/p>\n<p>mit Kopfh\u00f6rern, um sich in die Stimmung<\/p>\n<p>einer Kontemplativen zu versetzen.<\/p>\n<p>Auf einer Pelztrommel sa\u00df sie ohne zu st\u00f6ren<\/p>\n<p>trank gr\u00fcnen Tee, nachdem sie geh\u00f6rt hatte<\/p>\n<p>da\u00df er K\u00f6rper und Geist befl\u00fcgelt.<\/p>\n<p>&nbsp;<\/p>\n<p>Langm\u00fctig wartete sie auf ihre Befl\u00fcgelung<\/p>\n<p>um den V\u00f6geln<\/p>\n<p>nicht nur seelisch nah sein zu k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<p style=\"text-align: justify;\">Aus: <strong>Schwarz am Meer<\/strong>. Gedichte von Christiane Grosz. Friedrichshagen: Corvinus Presse, 2002 (Corvinus, 105. Druck. Reihe Welt statt Berlin, Bd. 12). Mit Zeichnungen der Autorin. (unpag.)<\/p>\n<div id=\"attachment_44595\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44595\" class=\"wp-image-44595 size-medium\" src=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2017\/09\/der-lyrik-eine-bresche-fuer-ein-gedicht-je-ausgabe-einer-zeitung_1505748323-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2017\/09\/der-lyrik-eine-bresche-fuer-ein-gedicht-je-ausgabe-einer-zeitung_1505748323-1-300x200.jpg 300w, http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2017\/09\/der-lyrik-eine-bresche-fuer-ein-gedicht-je-ausgabe-einer-zeitung_1505748323-1.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-44595\" class=\"wp-caption-text\">Poesie z\u00e4hlt f\u00fcr KUNO zu den identit\u00e4ts- und identifikationstiftenden Elementen der Kultur<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Weiterf\u00fchrend<\/strong> <strong>\u2192<\/strong> Poesie z\u00e4hlt f\u00fcr KUNO zu den identit\u00e4ts- und identifikationstiftenden Elementen der Kultur, dies bezeugt der Versuch einer <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=25630\">poetologischen Positionsbestimmung<\/a>. Um den Widerstand gegen die gepolsterte Gegenwartslyrik ein wenig anzufachen schickte <span data-offset-key=\"d96ve-1-0\">Wolfgang Schlott<\/span><span data-offset-key=\"d96ve-2-0\"> dieses\u00a0 post-dadaistische <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2016\/02\/03\/handwerkliche-anleitungen-zur-ueberwindung-von-schreibblockaden\/\">Manifest<\/a>. Warum<\/span> Lyrik wieder in die Zeitungen geh\u00f6rt <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/10\/07\/der-dichtung-eine-bresche-schlagen\/\">begr\u00fcndete<\/a> Walther Stonet, diese Forderung hat nichts an Aktualit\u00e4t verloren. Lesen Sie auch Maximilian Zanders <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=5418\">Essay <\/a>\u00fcber Lyrik und ein R\u00fcckblick auf den <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2014\/01\/08\/lyrik-katalog-bundesrepublik\/\"><em>Lyrik-Katalog Bundesrepublik<\/em><\/a>, sowie einen Essay \u00fcber den <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2013\/12\/26\/lauschender-leser-und-redender-schreiber-2\/\">Lyrikvermittler<\/a> Theo Breuer. KUNO sch\u00e4tzt den minuti\u00f6sen Selbstinszenierungsprozess des lyrischen Dichter-Ichs von Ulrich Bergmann in der Reihe <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=27947\">Keine Bojen auf hoher See, nur Sterne \u2026 und Schwerkraft. Gedanken \u00fcber das lyrische Schreiben<\/a>. Lesen Sie ein <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=22835\">Portr\u00e4t <\/a>\u00fcber die interdisziplin\u00e4re T\u00e4tigkeit von Angelika Janz, sowie einen <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=29450\">Essay<\/a> der <em>Fragmenttexterin.<\/em> Ein Portr\u00e4t von Sophie Reyer findet sich\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2013\/10\/08\/von-sappho-zu-sophie\/\">hier<\/a>, ein Essay fasst das transmediale Projekt<em> \u201e<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2021\/04\/14\/bi-textualitaet\/\">Wortspielhalle<\/a>\u201c <\/em>zusammen<em>. <\/em>Auf KUNO lesen Sie u.a. Rezensionsessays von <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2015\/06\/17\/beschwoerungszauber\/\">Holger Benkel<\/a> \u00fcber <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=15175\">Andr\u00e9 Schinkel<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/11\/12\/mit-deutschen-untertiteln\/\">Ralph Pordzik<\/a>,\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2018\/12\/20\/wohnraeume-der-poesie\/\">Friederike Mayr\u00f6cker<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/03\/19\/welten-gegenwelten\/\">Werner Weimar-Mazur<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2019\/06\/26\/wohnraeume-der-poesie-2\/\">Peter Engstler<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=15177\">Birgitt Lieberwirth<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2019\/08\/17\/der-grill-auf-der-hauswiese-der-welt\/\">Linda Vilhj\u00e1lmsd\u00f3ttir<\/a>, und <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/09\/17\/rettungsversuche-der-literatur-im-digitalen-raum\/\">A.J. Weigoni<\/a>. Lesenswert auch die <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2020\/05\/16\/verseschmied-und-lyrikfischer\/\">Gratulation<\/a> von Axel Kutsch durch Markus Peters zum 75. Geburtstag. Nicht zu vergessen eine Empfehlung der kristallklaren Lyrik von <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2020\/01\/19\/die-lyrikerin-ines-hagemeyer\/\">Ines Hagemeyer<\/a>. Diese Betrachtungen versammeln sich in der Tradition von <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2000\/04\/04\/vauo\/\">V.O. Stomps<\/a>, dem Klassiker des Andersseins, dem <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2005\/09\/24\/erinnerungen\/\">Bottroper Literaturrocker<\/a> &#8222;Biby&#8220; Wintjes und Hadayatullah H\u00fcbsch, dem Urvater des <a href=\"http:\/\/www.editiondaslabor.de\/blog\/1995\/06\/30\/wie-was-social-beat-ist-und-warum-und-warum-nicht\/\"><em>Social-Beat<\/em><\/a>, im KUNO-Online-Archiv. Wir empfehlen f\u00fcr Neulinge als Einstieg in das weite Feld der nonkonformistischen Literatur <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2001\/04\/01\/nonkonformistische-literatur\/\">diesem Hinweis<\/a> zu folgen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Katzenliteratur ist ihr ein Begriff. Gleich nach Grenz\u00f6ffnung suchte sie die esoterischen Teestuben auf kaufte wenig aber h\u00f6rte gern die Vogelstimmen mit Kopfh\u00f6rern, um sich in die Stimmung einer Kontemplativen zu versetzen. Auf einer Pelztrommel sa\u00df sie ohne&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"http:\/\/www.editiondaslabor.de\/blog\/2002\/10\/01\/alte-katze\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":44595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3318],"class_list":["post-97415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatur","tag-christiane-grosz"],"_links":{"self":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/97415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/comments?post=97415"}],"version-history":[{"count":0,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/97415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/"}],"wp:attachment":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media?parent=97415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/categories?post=97415"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/tags?post=97415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}