{"id":96970,"date":"1995-10-05T00:01:08","date_gmt":"1995-10-04T23:01:08","guid":{"rendered":"http:\/\/www.editiondaslabor.de\/blog\/?p=96970"},"modified":"2021-12-27T14:31:56","modified_gmt":"2021-12-27T13:31:56","slug":"mein-geschenk","status":"publish","type":"post","link":"http:\/\/www.editiondaslabor.de\/blog\/1995\/10\/05\/mein-geschenk\/","title":{"rendered":"Mein Geschenk"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Das Helle jagt das Dunkel, Grau das Blau:<\/p>\n<p>Ein Vorhang bl\u00e4ht sich, weht ganz kurz hinaus.<\/p>\n<p>Die Zeit hat sich ver\u00e4ndert. Ganz genau<\/p>\n<p>Versteht man\u2019s nicht. Im stillen, leeren Haus<\/p>\n<p>&nbsp;<\/p>\n<p>Geht deine Stimme, \u00f6ffnet jede T\u00fcr.<\/p>\n<p>Wenn ich im Zimmer ein Gedicht ersinne,<\/p>\n<p>Umgibt sie mich und schenkt mir, dass ich sp\u00fcr,<\/p>\n<p>Dass beim Verlieren selbst ich noch gewinne.<\/p>\n<p>&nbsp;<\/p>\n<p>Ich l\u00e4chle mir die Zweifel aus dem Denken,<\/p>\n<p>Als ich versonnen Deine Schritte z\u00e4hle<\/p>\n<p>Und diese mir die warme N\u00e4he schenken,<\/p>\n<p>Wenn ich mich mit der Fehlersuche qu\u00e4le.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Sonne schreibt den steten Tagesbogen:<\/p>\n<p>Du hast mich immer aus der Nacht gezogen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<div id=\"attachment_44595\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44595\" class=\"wp-image-44595 size-medium\" src=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2017\/09\/der-lyrik-eine-bresche-fuer-ein-gedicht-je-ausgabe-einer-zeitung_1505748323-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2017\/09\/der-lyrik-eine-bresche-fuer-ein-gedicht-je-ausgabe-einer-zeitung_1505748323-1-300x200.jpg 300w, http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2017\/09\/der-lyrik-eine-bresche-fuer-ein-gedicht-je-ausgabe-einer-zeitung_1505748323-1.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-44595\" class=\"wp-caption-text\">Poesie z\u00e4hlt f\u00fcr KUNO zu den identit\u00e4ts- und identifikationstiftenden Elementen der Kultur<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Weiterf\u00fchrend<\/strong> <strong>\u2192<\/strong> Poesie z\u00e4hlt f\u00fcr KUNO zu den identit\u00e4ts- und identifikationstiftenden Elementen der Kultur, dies bezeugt der Versuch einer <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=25630\">poetologischen Positionsbestimmung<\/a>. Um den Widerstand gegen die gepolsterte Gegenwartslyrik ein wenig anzufachen schickte <span data-offset-key=\"d96ve-1-0\">Wolfgang Schlott<\/span><span data-offset-key=\"d96ve-2-0\"> dieses\u00a0 post-dadaistische <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2016\/02\/03\/handwerkliche-anleitungen-zur-ueberwindung-von-schreibblockaden\/\">Manifest<\/a>. Warum<\/span> Lyrik wieder in die Zeitungen geh\u00f6rt <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/10\/07\/der-dichtung-eine-bresche-schlagen\/\">begr\u00fcndete<\/a> Walther Stonet, diese Forderung hat nichts an Aktualit\u00e4t verloren. Lesen Sie auch Maximilian Zanders <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=5418\">Essay <\/a>\u00fcber Lyrik und ein R\u00fcckblick auf den <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2014\/01\/08\/lyrik-katalog-bundesrepublik\/\"><em>Lyrik-Katalog Bundesrepublik<\/em><\/a>, sowie einen Essay \u00fcber den <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2013\/12\/26\/lauschender-leser-und-redender-schreiber-2\/\">Lyrikvermittler<\/a> Theo Breuer. KUNO sch\u00e4tzt den minuti\u00f6sen Selbstinszenierungsprozess des lyrischen Dichter-Ichs von Ulrich Bergmann in der Reihe <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=27947\">Keine Bojen auf hoher See, nur Sterne \u2026 und Schwerkraft. Gedanken \u00fcber das lyrische Schreiben<\/a>. Lesen Sie ein <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=22835\">Portr\u00e4t <\/a>\u00fcber die interdisziplin\u00e4re T\u00e4tigkeit von Angelika Janz, sowie einen <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=29450\">Essay<\/a> der <em>Fragmenttexterin.<\/em> Ein Portr\u00e4t von Sophie Reyer findet sich\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2013\/10\/08\/von-sappho-zu-sophie\/\">hier<\/a>, ein Essay fasst das transmediale Projekt<em> \u201e<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2021\/04\/14\/bi-textualitaet\/\">Wortspielhalle<\/a>\u201c <\/em>zusammen<em>. <\/em>Auf KUNO lesen Sie u.a. Rezensionsessays von <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2015\/06\/17\/beschwoerungszauber\/\">Holger Benkel<\/a> \u00fcber <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=15175\">Andr\u00e9 Schinkel<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/11\/12\/mit-deutschen-untertiteln\/\">Ralph Pordzik<\/a>,\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2018\/12\/20\/wohnraeume-der-poesie\/\">Friederike Mayr\u00f6cker<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/03\/19\/welten-gegenwelten\/\">Werner Weimar-Mazur<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2019\/06\/26\/wohnraeume-der-poesie-2\/\">Peter Engstler<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=15177\">Birgitt Lieberwirth<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2019\/08\/17\/der-grill-auf-der-hauswiese-der-welt\/\">Linda Vilhj\u00e1lmsd\u00f3ttir<\/a>, und <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/09\/17\/rettungsversuche-der-literatur-im-digitalen-raum\/\">A.J. Weigoni<\/a>. Lesenswert auch die <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2020\/05\/16\/verseschmied-und-lyrikfischer\/\">Gratulation<\/a> von Axel Kutsch durch Markus Peters zum 75. Geburtstag. Nicht zu vergessen eine Empfehlung der kristallklaren Lyrik von <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2020\/01\/19\/die-lyrikerin-ines-hagemeyer\/\">Ines Hagemeyer<\/a>. Diese Betrachtungen versammeln sich in der Tradition von <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2000\/04\/04\/vauo\/\">V.O. Stomps<\/a>, dem Klassiker des Andersseins, dem <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2005\/09\/24\/erinnerungen\/\">Bottroper Literaturrocker<\/a> &#8222;Biby&#8220; Wintjes und Hadayatullah H\u00fcbsch, dem Urvater des <a href=\"http:\/\/www.editiondaslabor.de\/blog\/1995\/06\/30\/wie-was-social-beat-ist-und-warum-und-warum-nicht\/\"><em>Social-Beat<\/em><\/a>, im KUNO-Online-Archiv. Wir empfehlen f\u00fcr Neulinge als Einstieg in das weite Feld der nonkonformistischen Literatur <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2001\/04\/01\/nonkonformistische-literatur\/\">diesem Hinweis<\/a> zu folgen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Das Helle jagt das Dunkel, Grau das Blau: Ein Vorhang bl\u00e4ht sich, weht ganz kurz hinaus. Die Zeit hat sich ver\u00e4ndert. Ganz genau Versteht man\u2019s nicht. Im stillen, leeren Haus &nbsp; Geht deine Stimme, \u00f6ffnet jede T\u00fcr. Wenn ich&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"http:\/\/www.editiondaslabor.de\/blog\/1995\/10\/05\/mein-geschenk\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":164,"featured_media":46597,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1972],"class_list":["post-96970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatur","tag-walther-stonet"],"_links":{"self":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/96970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/comments?post=96970"}],"version-history":[{"count":0,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/96970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/"}],"wp:attachment":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media?parent=96970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/categories?post=96970"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/tags?post=96970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}