{"id":62878,"date":"2020-11-01T00:01:00","date_gmt":"2020-10-31T23:01:00","guid":{"rendered":"http:\/\/www.editiondaslabor.de\/blog\/?p=62878"},"modified":"2021-02-24T06:04:38","modified_gmt":"2021-02-24T05:04:38","slug":"der-destruktive-charakter","status":"publish","type":"post","link":"http:\/\/www.editiondaslabor.de\/blog\/2020\/11\/01\/der-destruktive-charakter\/","title":{"rendered":"Der destruktive Charakter"},"content":{"rendered":"\r\n<p>&nbsp;<\/p>\r\n<p style=\"text-align: justify;\">Es k\u00f6nnte einem geschehen, da\u00df er, beim R\u00fcckblick auf sein Leben, zu der Erkenntnis k\u00e4me, fast alle tieferen Bindungen, die er in ihm erlitten habe, seien von Menschen ausgegangen, \u00fcber deren \u00bbdestruktiven Charakter\u00ab alle Leute sich einig waren. Er w\u00fcrde eines Tages, vielleicht zuf\u00e4llig, auf diese Tatsache sto\u00dfen, und je h\u00e4rter der Chock ist, der ihm so versetzt wird, desto gr\u00f6\u00dfer sind damit seine Chancen f\u00fcr eine Darstellung des destruktiven Charakters.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter kennt nur eine Parole: Platz schaffen; nur eine T\u00e4tigkeit: r\u00e4umen. Sein Bed\u00fcrfnis nach frischer Luft und freiem Raum ist st\u00e4rker als jeder Ha\u00df.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter ist jung und heiter. Denn Zerst\u00f6ren verj\u00fcngt, weil es die Spuren unseres eigenen Alters aus dem Weg r\u00e4umt; es heitert auf, weil jedes Wegschaffen dem Zerst\u00f6renden eine vollkommene Reduktion, ja Radizierung seines eignen Zustands bedeutet. Zu solchem apollinischen Zerst\u00f6rerbilde f\u00fchrt erst recht die Einsicht, wie ungeheuer sich die Welt vereinfacht, wenn sie auf ihre Zerst\u00f6rungsw\u00fcrdigkeit gepr\u00fcft wird. Dies ist das gro\u00dfe Band, das alles Bestehende eintr\u00e4chtig umschlingt. Das ist ein Anblick, der dem destruktiven Charakter ein Schauspiel tiefster Harmonie verschafft.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter ist immer frisch bei der Arbeit. Die Natur ist es, die ihm das Tempo vorschreibt, indirekt wenigstens: denn er mu\u00df ihr zuvorkommen. Sonst wird sie selber die Zerst\u00f6rung \u00fcbernehmen.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Dem destruktiven Charakter schwebt kein Bild vor. Er hat wenig Bed\u00fcrfnisse, und das w\u00e4re sein geringstes: zu wissen, was an Stelle des Zerst\u00f6rten tritt. Zun\u00e4chst, f\u00fcr einen Augenblick zumindest, der leere Raum, der Platz, wo das Ding gestanden, das Opfer gelebt hat. Es wird sich schon einer finden, der ihn braucht, ohne ihn einzunehmen.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter tut seine Arbeit, er vermeidet nur sch\u00f6pferische. So wie der Sch\u00f6pfer Einsamkeit sich sucht, mu\u00df der Zerst\u00f6rende fortdauernd sich mit Leuten, mit Zeugen seiner Wirksamkeit umgeben.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter ist ein Signal. So wie ein trigonometrisches Zeichen von allen Seiten dem Winde, ist er von allen Seiten dem Gerede ausgesetzt. Dagegen ihn zu sch\u00fctzen, ist sinnlos.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter ist gar nicht daran interessiert, verstanden zu werden. Bem\u00fchungen in dieser Richtung betrachtet er als oberfl\u00e4chlich. Das Mi\u00dfverstandenwerden kann ihm nichts anhaben. Im Gegenteil, er fordert es heraus, wie die Orakel, diese destruktiven Staatseinrichtungen, es herausgefordert haben. Das kleinb\u00fcrgerlichste aller Ph\u00e4nomene, der Klatsch, kommt nur zustande, weil die Leute nicht mi\u00dfverstanden werden wollen. Der destruktive Charakter l\u00e4\u00dft sich mi\u00dfverstehen; er f\u00f6rdert den Klatsch nicht.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter ist der Feind des Etui-Menschen. Der Etui-Mensch sucht seine Bequemlichkeit, und das Geh\u00e4use ist ihr Inbegriff. Das Innere des Geh\u00e4uses ist die mit Samt ausgeschlagene Spur, die er in die Welt gedr\u00fcckt hat. Der destruktive Charakter verwischt sogar die Spuren der Zerst\u00f6rung.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter steht in der Front der Traditionalisten. Einige \u00fcberliefern die Dinge, indem sie sie unantastbar machen und konservieren, andere die Situationen, indem sie sie handlich machen und liquidieren. Diese nennt man die Destruktiven.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter hat das Bewu\u00dftsein des historischen Menschen, dessen Grundaffekt ein unbezwingliches Mi\u00dftrauen in den Gang der Dinge und die Bereitwilligkeit ist, mit der er jederzeit davon Notiz nimmt, da\u00df alles schief gehen kann. Daher ist der destruktive Charakter die Zuverl\u00e4ssigkeit selbst.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter sieht nichts Dauerndes. Aber eben darum sieht er \u00fcberall Wege. Wo andere auf Mauern oder Gebirge sto\u00dfen, auch da sieht er einen Weg. Weil er aber \u00fcberall einen Weg sieht, hat er auch \u00fcberall aus dem Weg zu r\u00e4umen. Nicht immer mit roher Gewalt, bisweilen mit veredelter. Weil er \u00fcberall Wege sieht, steht er selber immer am Kreuzweg. Kein Augenblick kann wissen, was der n\u00e4chste bringt. Das Bestehende legt er in Tr\u00fcmmer, nicht um der Tr\u00fcmmer, sondern um des Weges willen, der sich durch sie hindurchzieht.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Der destruktive Charakter lebt nicht aus dem Gef\u00fchl, da\u00df das Leben lebenswert sei, sondern da\u00df der Selbstmord die M\u00fche nicht lohnt.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">Das letzte Gedicht der \u00bbFleurs du mal\u00ab: Le Voyage \u00bbO mort, vieux capitaine, il est temps, levons l&#8217;ancre.\u00ab Die letzte Reise des Flaneurs: der Tod. Ihr Ziel: das Neue. \u00bbAu fond de l&#8217;inconnu pour trouver du nouveau.\u00ab Das Neue ist eine vom Gebrauchswert der Ware unabh\u00e4ngige Qualit\u00e4t. Es ist der Ursprung des Scheins, der den Bildern unver\u00e4u\u00dferlich ist, die das kollektive Unbewu\u00dfte hervorbringt. Es ist die Quintessenz des falschen Bewu\u00dftseins, dessen nimmerm\u00fcde Agentin die Mode ist. Dieser Schein des Neuen reflektiert sich, wie ein Spiegel im andern, im Schein des immer wieder Gleichen. Das Produkt dieser Reflexion ist die Phantasmagorie der \u00bbKulturgeschichte\u00ab, in der die Bourgeoisie ihr falsches Bewu\u00dftsein auskostet. Die Kunst, die an ihrer Aufgabe zu zweifeln beginnt und aufh\u00f6rt \u00bbins\u00e9parable de l&#8217;utilit\u00e9\u00ab zu sein (Baudelaire), mu\u00df das Neue zu ihrem obersten Wert machen. Der arbiter novarum rerum wird ihr der Snob. Er ist der Kunst, was der Mode der Dandy ist. \u2014 Wie im siebzehnten Jahrhundert die Allegorie der Kanon der dialektischen Bilder wird, so im neunzehnten Jahrhundert die Nouveaut\u00e9. Den magasins de nouveaut\u00e9 treten die Zeitungen an die Seite. Die Presse organisiert den Markt geistiger Werte, auf dem zun\u00e4chst eine Hausse entsteht. Die Nonkonformisten rebellieren gegen die Auslieferung der Kunst an den Markt. Sie scharen sich um das Banner des \u00bbl&#8217;art pour l&#8217;art\u00ab. Dieser Parole entspringt die Konzeption des Gesamtkunstwerks, das versucht, die Kunst gegen die Entwicklung der Technik abzudichten. Die Weihe, mit der es sich zelebriert, ist das Pendant der Zerstreuung, die die Ware verkl\u00e4rt. Beide abstrahieren vom gesellschaftlichen Dasein des Menschen. Baudelaire unterliegt der Bet\u00f6rung Wagners.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-large-font-size\" style=\"text-align: justify;\">\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\">***<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\" style=\"text-align: justify;\">\r\n<figure class=\"alignleft\"><a href=\"http:\/\/www.editiondaslabor.de\/blog\/wp-admin\/media-upload.php?post_id=15724&amp;type=image&amp;TB_iframe=1\"><img decoding=\"async\" class=\"alignleft\" src=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2013\/05\/220px-Walter_Benjamin_vers_1928.jpg\" alt=\"\" \/><\/a>\r\n<p>Zum 80. Todestag von Walter Benjamin erinnert KUNO an diesen undogmatischen Denker und l\u00e4\u00dft die Originalit\u00e4t und Einzigartigkeit seiner Gedanken aufscheinen. Bei KUNO pr\u00e4sentieren wir Essays \u00fcber den Zwischenraum von Denken und Dichten, wobei das Denken von der Sprache kaum zu l\u00f6sen ist. Lesen Sie auch KUNOs <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2013\/12\/10\/zur-gattung-essay\/\">Hommage<\/a> an die Gattung des Essays.<\/p>\r\n<p><strong>Weiterf\u00fchrend\u00a0\u2192 <\/strong>ein Essay \u00fcber die neue Literaturgattung <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=22423\"><em>Twitteratur<\/em><\/a>.<\/p>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Es k\u00f6nnte einem geschehen, da\u00df er, beim R\u00fcckblick auf sein Leben, zu der Erkenntnis k\u00e4me, fast alle tieferen Bindungen, die er in ihm erlitten habe, seien von Menschen ausgegangen, \u00fcber deren \u00bbdestruktiven Charakter\u00ab alle Leute sich einig waren. Er&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"http:\/\/www.editiondaslabor.de\/blog\/2020\/11\/01\/der-destruktive-charakter\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":72,"featured_media":11330,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[428],"class_list":["post-62878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatur","tag-walter-benjamin"],"_links":{"self":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/62878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/comments?post=62878"}],"version-history":[{"count":0,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/62878\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/"}],"wp:attachment":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media?parent=62878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/categories?post=62878"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/tags?post=62878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}