{"id":47814,"date":"1998-05-24T00:01:49","date_gmt":"1998-05-23T22:01:49","guid":{"rendered":"http:\/\/www.editiondaslabor.de\/blog\/?p=47814"},"modified":"2021-10-09T16:16:22","modified_gmt":"2021-10-09T14:16:22","slug":"passage","status":"publish","type":"post","link":"http:\/\/www.editiondaslabor.de\/blog\/1998\/05\/24\/passage\/","title":{"rendered":"Passage"},"content":{"rendered":"<div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u201eDie Arbeit \u00fcber die Passagen setzt ein immer r\u00e4tselhafteres, eindringlicheres Gesicht auf und heult nach Art einer kleinen Bestie in meine N\u00e4chte, wenn ich sie tags\u00fcber nicht an den entlegensten Quellen getr\u00e4nkt habe. Wei\u00df Gott was sie anrichtet, wenn ich sie eines Tages frei lasse.\u201c<\/p>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: center;\">***<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\n<div style=\"width: 208px\" class=\"wp-caption alignleft\"><a id=\"set-post-thumbnail\" class=\"thickbox\" href=\"http:\/\/www.editiondaslabor.de\/blog\/wp-admin\/media-upload.php?post_id=47814&amp;type=image&amp;TB_iframe=1\" aria-describedby=\"set-post-thumbnail-desc\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-266x266\" src=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2028\/05\/Passage_de_lOpe\u0301ra.jpg\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" srcset=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2028\/05\/Passage_de_lOpe\u0301ra.jpg 338w, http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2028\/05\/Passage_de_lOpe\u0301ra-223x300.jpg 223w\" alt=\"\" width=\"198\" height=\"266\" \/><\/a><p class=\"wp-caption-text\">Passage de l&#8217;Op\u00e9ra (Galerie du Barom\u00e8tre), IXe arrondissement, Paris, France, vers 1909<\/p><\/div>\n<p>Quelle: Aus einem Brief an Gershom Scholem vom 24. Mai 1928. Der Titel <i>Passagen\u00a0<\/i> geht zur\u00fcck auf die \u00fcberdachten Ladenpassagen, die ab dem fr\u00fchen neunzehnten Jahrhundert zun\u00e4chst in Paris entstanden. Benjamin sammelte als Flaneur &#8211; und diesen Begriff f\u00fcllend &#8211; Hintergr\u00fcnde \u00fcber ebendiese Pariser Passagen, Stra\u00dfen und Warenh\u00e4user, auch Panoramen und Weltausstellungen, schrieb seine Gedanken \u00fcber Mode, Prostitution und Reklame auf und wollte eine <i>dialektische Feerie<\/i> entwerfen, in der die Entwicklung des Kapitalismus anhand der Lebenswelten der Metropole illustriert wird.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u201eDie Arbeit \u00fcber die Passagen setzt ein immer r\u00e4tselhafteres, eindringlicheres Gesicht auf und heult nach Art einer kleinen Bestie in meine N\u00e4chte, wenn ich sie tags\u00fcber nicht an den entlegensten Quellen getr\u00e4nkt habe. Wei\u00df Gott was sie anrichtet, wenn&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"http:\/\/www.editiondaslabor.de\/blog\/1998\/05\/24\/passage\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":72,"featured_media":47816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[428],"class_list":["post-47814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatur","tag-walter-benjamin"],"_links":{"self":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/47814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/comments?post=47814"}],"version-history":[{"count":0,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/47814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/"}],"wp:attachment":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media?parent=47814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/categories?post=47814"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/tags?post=47814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}