{"id":38198,"date":"1993-11-14T00:01:59","date_gmt":"1993-11-13T23:01:59","guid":{"rendered":"http:\/\/www.editiondaslabor.de\/blog\/?p=38198"},"modified":"2023-07-17T06:00:58","modified_gmt":"2023-07-17T04:00:58","slug":"lage-2","status":"publish","type":"post","link":"http:\/\/www.editiondaslabor.de\/blog\/1993\/11\/14\/lage-2\/","title":{"rendered":"LAGE"},"content":{"rendered":"<p align=\"center\">\n<p align=\"center\">spring ich ins licht ist es<\/p>\n<p align=\"center\">ein spiegel bin ich geblendet wei\u00df<\/p>\n<p align=\"center\">vom schein der scherben<\/p>\n<p align=\"center\">st\u00fcrzen golden die bl\u00e4tter<\/p>\n<p align=\"center\">und mond\u00e4ugig die worte mir<\/p>\n<p align=\"center\">ins gesicht tanzen die splitter<\/p>\n<p align=\"center\">seh ich hinterm glas geronnen<\/p>\n<p align=\"center\">die entfallne seele leuchten<\/p>\n<p align=\"center\">als kristall greif ich wie<\/p>\n<p align=\"center\">nach ger\u00f6ll unters fleisch<\/p>\n<p align=\"center\">mir kehr ich die h\u00e4ute um<\/p>\n<p align=\"center\">wo einst die stirn lag ragen knochen<\/p>\n<p align=\"center\">in den wind der lautlos leicht<\/p>\n<p align=\"center\">die gardine streift hoch oben<\/p>\n<p align=\"center\">im offenen winkel des raumes<\/p>\n<p align=\"center\">***<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Vorschau auf den Gedichtband <strong>kindheit und kadaver<\/strong>, Gedichte von Holger Benkel, mit Radierungen von Jens Eigner. Verlag Blaue \u00c4pfel, Magdeburg 1995. Eine Rezension des ersten Gedichtbandes von Holger Benkel finden Sie<a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=6898\"> hier<\/a>.<\/p>\n<p><b><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-98901 alignleft\" src=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2025\/12\/Kindheit-und-Kadaver-Cover.jpg\" alt=\"\" width=\"140\" height=\"221\" \/>Weiterf\u00fchrend <\/b><b>\u2192<\/b><\/p>\n<p style=\"text-align: justify;\">In einem <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=29373\">Kollegengespr\u00e4ch<\/a> ergr\u00fcndeln Holger Benkel und A.J. Weigoni das Wesen der Poesie &#8211; und ihr allm\u00e4hliches Verschwinden. Das erste Kollegengespr\u00e4ch zwischen Holger Benkel und Weigoni finden Sie <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=29373\">hier<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Gedanken, die um Ecken biegen<\/strong>, Aphorismen von Holger Benkel, <a href=\"http:\/\/www.editiondaslabor.de\/\">Edition Das Labor<\/a>, M\u00fclheim 2013<\/p>\n<p style=\"text-align: justify;\"><b>Essays<\/b> von Holger Benkel, Edition Das Labor 2014 \u2013 Einen Hinweis auf die in der Edition Das Labor erschienen Essays finden Sie <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=21478\">hier<\/a>.\u00a0Auf KUNO portr\u00e4tierte Holger Benkel die <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=11282\">Br\u00fcder Grimm<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=6837\">Ulrich Bergmann<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=11284\">A.J. Weigoni<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=11279\">Uwe Albert<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=15175\">Andr\u00e9 Schinkel<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=15177\">Birgitt Lieberwirth<\/a> und <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=15179\">Sabine Kunz<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>spring ich ins licht ist es ein spiegel bin ich geblendet wei\u00df vom schein der scherben st\u00fcrzen golden die bl\u00e4tter und mond\u00e4ugig die worte mir ins gesicht tanzen die splitter seh ich hinterm glas geronnen die entfallne seele leuchten als&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"http:\/\/www.editiondaslabor.de\/blog\/1993\/11\/14\/lage-2\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":36,"featured_media":98901,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[94],"class_list":["post-38198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatur","tag-holger-benkel"],"_links":{"self":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/38198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/comments?post=38198"}],"version-history":[{"count":2,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/38198\/revisions"}],"predecessor-version":[{"id":104870,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/38198\/revisions\/104870"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media\/98901"}],"wp:attachment":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media?parent=38198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/categories?post=38198"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/tags?post=38198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}