{"id":28111,"date":"1995-10-06T00:01:12","date_gmt":"1995-10-05T23:01:12","guid":{"rendered":"http:\/\/www.editiondaslabor.de\/blog\/?p=28111"},"modified":"2022-02-28T06:40:13","modified_gmt":"2022-02-28T05:40:13","slug":"anleitung","status":"publish","type":"post","link":"http:\/\/www.editiondaslabor.de\/blog\/1995\/10\/06\/anleitung\/","title":{"rendered":"ANLEITUNG"},"content":{"rendered":"<p>&nbsp;<\/p>\r\n<p>Wenn Sie ein Gedicht lesen,<\/p>\r\n<p>dann lesen Sie es am besten so,<\/p>\r\n<p>sehen Sie, so.<\/p>\r\n<p>Selbstverst\u00e4ndlich k\u00f6nnen Sie<\/p>\r\n<p>es auch anders lesen.<\/p>\r\n<p>Es gibt verschiedene M\u00f6glichkeiten.<\/p>\r\n<p>Beispielsweise so.<\/p>\r\n<p>Oder so.<\/p>\r\n<p>Ich habe einen Mann gekannt,<\/p>\r\n<p>der Gedichte so las.<\/p>\r\n<p>Aber er war eine Ausnahme.<\/p>\r\n<p>Die meisten lesen Gedichte so.<\/p>\r\n<p>Ja, genau so.<\/p>\r\n<p>Haben Sie schon einmal<\/p>\r\n<p>ein Gedicht so gelesen?<\/p>\r\n<p>Nein, nicht so, sondern so.<\/p>\r\n<p>Ich sage Ihnen, es bringt nicht viel,<\/p>\r\n<p>wenn man ein Gedicht so liest.<\/p>\r\n<p>Man liest es besser so.<\/p>\r\n<p>Verbindliche Regeln gibt es nicht.<\/p>\r\n<p>Aber glauben Sie mir:<\/p>\r\n<p>Sie haben mehr von einem Gedicht,<\/p>\r\n<p>wenn Sie es so lesen \u2013<\/p>\r\n<p>sehen Sie, so.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p>&nbsp;<\/p>\r\n<!-- \/wp:post-content -->\r\n\r\n<!-- wp:paragraph {\"align\":\"center\"} -->\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\">***<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:image {\"align\":\"left\",\"linkDestination\":\"custom\"} -->\r\n<div class=\"wp-block-image\">\r\n<figure class=\"alignleft\"><a href=\"http:\/\/www.editiondaslabor.de\/blog\/wp-admin\/media-upload.php?post_id=28105&amp;type=image&amp;TB_iframe=1\"><img decoding=\"async\" src=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2013\/12\/Axel-Kutsch.jpeg\" alt=\"\" \/><\/a><\/figure>\r\n<\/div>\r\n<!-- \/wp:image -->\r\n\r\n<!-- wp:paragraph -->\r\n<p style=\"text-align: justify;\">Eine \u00a0W\u00fcrdigung des Herausgebers und Lyrikers Axel Kutsch im Kreise von Autoren aus Metropole und Hinterland <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=12833\">hier<\/a>. Poesie z\u00e4hlt f\u00fcr KUNO weiterhin zu den identit\u00e4ts- und identifikationstiftenden Elementen einer Kultur, dies bezeugte auch der Versuch einer <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=25630\">poetologischen Positionsbestimmung<\/a>.<\/p>\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Wenn Sie ein Gedicht lesen, dann lesen Sie es am besten so, sehen Sie, so. Selbstverst\u00e4ndlich k\u00f6nnen Sie es auch anders lesen. Es gibt verschiedene M\u00f6glichkeiten. Beispielsweise so. Oder so. Ich habe einen Mann gekannt, der Gedichte so las.&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"http:\/\/www.editiondaslabor.de\/blog\/1995\/10\/06\/anleitung\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[104],"class_list":["post-28111","post","type-post","status-publish","format-standard","hentry","category-literatur","tag-axel-kutsch"],"_links":{"self":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/28111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/comments?post=28111"}],"version-history":[{"count":1,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/28111\/revisions"}],"predecessor-version":[{"id":99585,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/28111\/revisions\/99585"}],"wp:attachment":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media?parent=28111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/categories?post=28111"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/tags?post=28111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}