{"id":17055,"date":"2021-07-20T00:01:00","date_gmt":"2021-07-19T22:01:00","guid":{"rendered":"http:\/\/www.editiondaslabor.de\/blog\/?p=17055"},"modified":"2022-03-07T12:42:41","modified_gmt":"2022-03-07T11:42:41","slug":"%e2%80%a1-zwischenbefund-%e2%80%a1","status":"publish","type":"post","link":"http:\/\/www.editiondaslabor.de\/blog\/2021\/07\/20\/%e2%80%a1-zwischenbefund-%e2%80%a1\/","title":{"rendered":"\u2021 Zwischenbefund \u2021"},"content":{"rendered":"<p><em>\u00a0<\/em><\/p>\n<p>die Sprache<\/p>\n<p>hat das<\/p>\n<p>Sagen<\/p>\n<p>:<\/p>\n<p>progressive Paralyse<\/p>\n<p>anhaltender Satzdurchfall<\/p>\n<p>Worte<\/p>\n<p>wertloser als<\/p>\n<p>abgestempelte Fahrkarten<\/p>\n<p>welche wenigstens eindeutige<\/p>\n<p>Richtungen bestimmen<\/p>\n<p>raschelndes Papier<\/p>\n<p>berauschendes Buchstabengest\u0153ber<\/p>\n<p>nach Wirklichkeit wird<\/p>\n<p>weiterhin im Nebel gestochert<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\" align=\"center\">***<\/p>\n<p style=\"text-align: justify;\"><strong>Dichterloh<\/strong> ist in der LYRIKEDITION 2000 erschienen und erh\u00e4ltlich \u00fcber: info(@)buchmedia.de<\/p>\n<p style=\"text-align: justify;\">Die Rezitation ist erschienen auf <strong>Gedichte<\/strong>, H\u00f6rbuch von A.J. Weigoni, Edition Das Labor, M\u00fclheim 2015 \u2013 Eine H\u00f6rprobe aus <em>Dichterloh<\/em> findet sich <a href=\"http:\/\/www.vordenker.de\/weigoni\/dichterloh.htm\">hier<\/a>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2013\/12\/Dichterloh.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12679\" src=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2013\/12\/Dichterloh.jpg\" alt=\"\" width=\"124\" height=\"191\" \/><\/a><strong>Weiterf\u00fchrend <\/strong><strong>\u2192<\/strong><strong>\u00a0<\/strong>Das H\u00f6rbuch\u00a0<em>Dichterloh<\/em>\u00a0ist im\u00a0<em>Schuber<\/em>\u00a0enthalten, einem Sammlerobjekt, jedes Titelbild ist ein Kunstwerk. KUNO fa\u00dft die\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/12\/10\/das-lyrische-gesamtwerk-fini\/\">Stimmen<\/a>\u00a0zu dieser verlegerischen Gro\u00dftat zusammen.\u00a0Im Rahmen der Publikation des lyrischen Gesamtwerks des <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2015\/01\/18\/das-gesamtwerk-des-sprechstellers\/\"><em>Sprechstellers<\/em><\/a> blickt\u00a0Ulrich Bergmann auf den Mittelteil der Trilogie\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/03\/18\/letternmusik-eine-partitur\/\">Letternmusik<\/a>,\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2015\/12\/09\/der-sprache-aufs-maul-schauen\/\">Schmauchspuren<\/a>\u00a0\u2013 eine Todeslitanei, und\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/06\/18\/dichte-lohe-2\/\">Dichterloh<\/a>\u00a0\u2013 Kompositum in vier Akten, zur\u00fcck. \u00dcber den Sinn einer\u00a0Lesung,\u00a0eine\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=28705\">Reflexion<\/a> von Weigoni.\u00a0Last but not least:\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2005\/01\/18\/verdichtung-ueber-das-verfertigen-von-poesie\/\"><em>VerDichtung \u2013 \u00dcber das Verfertigen von Poesie<\/em><\/a>, ein Essay von A.J. Weigoni in dem er dichtungstheoretisch die poetologischen Grunds\u00e4tze seines Schaffens beschreibt.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 die Sprache hat das Sagen : progressive Paralyse anhaltender Satzdurchfall Worte wertloser als abgestempelte Fahrkarten welche wenigstens eindeutige Richtungen bestimmen raschelndes Papier berauschendes Buchstabengest\u0153ber nach Wirklichkeit wird weiterhin im Nebel gestochert &nbsp; &nbsp; &nbsp; &nbsp; *** Dichterloh ist in&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"http:\/\/www.editiondaslabor.de\/blog\/2021\/07\/20\/%e2%80%a1-zwischenbefund-%e2%80%a1\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":14,"featured_media":99364,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[628],"class_list":["post-17055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatur","tag-a-j-weigoni"],"_links":{"self":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/17055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/comments?post=17055"}],"version-history":[{"count":2,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/17055\/revisions"}],"predecessor-version":[{"id":102077,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/17055\/revisions\/102077"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media\/99364"}],"wp:attachment":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media?parent=17055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/categories?post=17055"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/tags?post=17055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}