{"id":104905,"date":"2003-02-02T13:21:15","date_gmt":"2003-02-02T12:21:15","guid":{"rendered":"http:\/\/www.editiondaslabor.de\/blog\/?p=104905"},"modified":"2023-08-06T13:23:53","modified_gmt":"2023-08-06T11:23:53","slug":"das-biografische-gesicht-unter-verschluss","status":"publish","type":"post","link":"http:\/\/www.editiondaslabor.de\/blog\/2003\/02\/02\/das-biografische-gesicht-unter-verschluss\/","title":{"rendered":"Das biografische Gesicht unter Verschluss"},"content":{"rendered":"<p style=\"text-align: right;\">Rue Vieille du Temple, Paris.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Kleine L\u00e4den, schmutzige Schaufensterscheiben. Dahinter verh\u00f6hnen seltsame Pr\u00e4sentationen den Abstand des Flaneurs zu den Gelassen stiller Rituale. Sie ziehen dich in Intimit\u00e4t, in vertrauliche Zusammenh\u00e4nge hinein, die man riechen kann. Alles Hingestellte, Ausgestellte, wirkt vorl\u00e4ufig, oder andersherum: wie l\u00e4ngt \u00fcberholt, viel zu lange schon zur Schau gestellt.<\/p>\n<p style=\"text-align: justify;\">Flitterb\u00e4nder kr\u00e4useln Pastell- und Karostoffe, eine zeitlose Mode umschmeichelt proportionierte, etwas abgegriffene Gestelle, Prothesenleiber, Attrappensch\u00f6nheiten.<\/p>\n<p style=\"text-align: justify;\">Du bist da, in dieser Pariser Kurzatmigkeit, ein wei\u00dfes Blutk\u00f6rperchen von zu vielen wei\u00dfen im an\u00e4mischen Blutstrom der Stadt.<\/p>\n<p style=\"text-align: justify;\">Ein Insekt im Harz, das, immer noch zappelnd, langsam erstarrt, und ist es einmal ganz fest, ist ein Auge eingesperrt f\u00fcr staunende Augen: Exiltr\u00e4ume.<\/p>\n<p style=\"text-align: justify;\">Du parierst einem fremden Blick, den Blick einer Schaufensterpuppe aus der Richtung rue du Tresor, auf der anderen Seite, einer Sackgasse. Die Puppe ist die Nachbildung eines vielleicht 10-j\u00e4hrigen weiblichen Menschenwesens. Das ist der Fleck in deinem Ged\u00e4chtnis, ein verblassender Fleck, du sch\u00e4mst dich nicht, weil er da ist, sondern weil du jetzt \u00fcber ihn sprechen willst und es dir unm\u00f6glich erscheint, ihn deinen gewohnten Ordnungen preiszugeben, als sei er ein Souvenir oder das Fragment einer schlecht erz\u00e4hlten Anekdote. Du versp\u00fcrtest ein Unbehagen. Die Sprache hat sich daran gew\u00f6hnt, das Fremde als das Exotische zu bezeichnen, zu bezeichnen mit changierenden erotischen Tupfern auf einer etwas br\u00fcchig gewordenen, aber immer noch sehns\u00fcchtig Atem holenden Haut.<\/p>\n<p style=\"text-align: justify;\">Das leicht wie nach heftigem Weinen aufgedunsen erscheinende Gesicht der M\u00e4dchenpuppe ist von br\u00e4unlicher, wie bei Tierfleisch angesengter F\u00e4rbung,\u00a0 stark farbige Konturierung seiner Gesichtsz\u00fcge ersetzt Tiefensch\u00e4rfe . Nicht einmal die H\u00e4nde sind richtig gesehen, w\u00fcrde der K\u00fcnstler sagen, Stummelh\u00e4nde, St\u00fcmmelwunder, zu knolligen F\u00e4ustchen geballt, den Rundh\u00f6lzern des K\u00f6rperger\u00fcstes in Pulsh\u00f6he aufgesteckt, von den Fl\u00fcgel\u00e4rmeln des altbacken unmodischen Kleides freigegeben. In der ersten Sekunde des Vor\u00fcbergehens, deren Reizantrieb der Verrat, Selbstverrat und deren Wirkdauer wie Luxus ist, Zeitluxus, denkst du an modelliertes Eis, weil dir nichts Besseres einkommt. Du l\u00e4sst es schmelzen, Eiswasser. Eisluft, Eiserde, das f\u00fcllt dich langsam leise an. Du w\u00fcnschst Umnachtung n\u00e4chtlich schnell. Es wird umsonst sein. Ein negatives D\u00e9j\u00e0-vu .<\/p>\n<p style=\"text-align: justify;\">Du begannst etwas vor Dich hin zu stammeln. Wer stammelt, bringt meist \u00a0noch einen Sinn zustande. Du aber kommst nicht einmal mit diesem Wort zurande: GESICHT, das es gar nicht gibt. Ja, das hast Du versucht zu sagen. Ein leicht irritiertes, vielleicht ein\u00a0 fremd modelliertes Durchschnittsgesicht: aber darf ich so \u00fcber ein Kindergesicht sprechen? Du bist ungerecht, siehst etwas, das dir wenig sympathisch ist, aber die br\u00fcnette Frisur ist so exakt, so authentisch in Wellen gelegt, <em>Sehnsuchtswellen der Kindheit<\/em>, von denen du wei\u00dft, dass sie nicht wieder und wieder zusammenfallen, sondern verstauben werden. Gab es einmal ein Gesicht wie dieses ? Ich muss es entschieden verneinen, weil mich das Grauen bei dieser Vorstellung sanftm\u00fctig streift. Weder kann es ein Vorbild geben, noch kann es sich bei dieser Wachsmodellierung um eine Nachahmung oder auch nur um eine dilettantische Nachempfindung handeln. <em>Dieses Gesicht ist die reine Erfindung<\/em>, und als dieser so selbstverst\u00e4ndliche Gedanke mich erreicht hatte, fand ich ihn obsz\u00f6n wie das, was er vorstellte. Gebrochen waren alle seine Z\u00fcge, gebrochen war dieses puppenhaft k\u00fcnstliche Wesen.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00dcberraschend bewegte sich hinter der Puppe im angrenzenden Verkaufsraum des Schaufensters eine junge Verk\u00e4uferin, und ich <em>erschrak, weil sie ein Mensch war<\/em>. Auff\u00e4llig war ihre\u00a0 Hakennase, sie rauchte eine Zigarette, posierte zwischen den Regalen <em>wie rein\u00a0 zuf\u00e4llig<\/em>, und wie ich jetzt erkennen konnte, waren die aus braunem, schweren Holz gebauten Regale angef\u00fcllt mit minderwertigen Posamenten, Material, das du in jeder M\u00fcllt\u00fcte finden kannst, und die junge Verkaufsdame strahlte all die ihrer Aura zur Verf\u00fcgung stehende Ver\u00e4chtlichkeit f\u00fcr diese Gegenst\u00e4nde ihres vielleicht erzwungenen Berufes aus. Ihr Aufenthalt in dieser trostlosen Szenerie musste einen ganzen Arbeitstag lang und einen immer wieder weiteren Arbeitstag lang vielleicht \u00fcber Jahre hinweg dunkel und vorl\u00e4ufig bleiben. W\u00fcrde man, mit dieser <em>Abschreckung <\/em>im Schaufenster, \u00fcberhaupt je etwas verkaufen k\u00f6nnen?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Es gibt Unterschiede zwischen M\u00f6bel und Stuhl, Hund und Dackel, Obst und Birne, zwischen Kunst und einem Gedicht. So innig war bei diesem Gesicht, das mich auf seine obsz\u00f6ne Art zu verh\u00f6hnen schien, der denkbare Unterschied zum Lebendigen. Durch das Wort ist dieses <em>Phantom<\/em> allein sprachlich da. Es hat alle Fortschritte in der Literatur einbegriffen, aber wo ist der Fortschritt hingegangen? Als Schritt hat er doch zu irgendwas, zu irgendwem gef\u00fchrt?!: Er ist auf die eigene Biografie zugeschritten, ich habe in dem Schaufenster mein <em>eigenes Gesicht<\/em> gesehen, mein Kindergesicht, k\u00fcnstlich, aus Wachs, mit Farbe angepinselt und beklebt mit einem Staubmagnet, der gewellten Kunsthaarfrisur. Der Zwang, die Ausweglosigkeit eines Leugnens, das sei nicht ich, erkennen zu m\u00fcssen und die gleichzeitige, Ekel und Scham erzeugende Absto\u00dfung dieser materialen Erscheinung schraubte mich f\u00fcr lange Augenblicke in den weltst\u00e4dtischen Boden vor diesem streifig geputzten Schaufenster, hinter dem die Wahrheit mein Einverst\u00e4ndnis abforderte. Jetzt, da die Experimentierphase vorbei ist, da die Welt so ist, wie ich sie mir in fr\u00fcher Jugend erdacht habe! Jetzt zeigt sich, wer niemals Meister war, die Dinge beginnen sich zu f\u00fcgen! Jetzt ist das Skelett da, der Strang, der rote Faden, der sich durch die modellhafte Erinnerung zieht. Dieses Gesicht sagt mir, dass ich, ohne je auf Mitleid zu sto\u00dfen, auf eine ungesunde Weise verst\u00f6rt gewesen sein musste, als ich die ersten Zeilen aus Seelenhunger, Seelennot, niedergeschrieben hatte in ein mutma\u00dflich verschlie\u00dfbares, kunstledernes Tagebuch: Dieses sp\u00e4te Experiment ist eine Jugends\u00fcnde! Und s\u00fcndig ist dieses Gesicht, so schmerzhaft allgemein, so sehr vages Zitat ohne Verfasserangabe, so abtr\u00fcnnig, so \u00fcberformt, so leer wie verw\u00fcstet und so entsetzlich verloren wie instinktiv verlogen! Um es zusammenzufassen: es war ein gemeines Gesicht in all seiner Unschuld, weil es seiner Zeit voraus war. Wozu a\u00df das stille Kind jahrelang sein braun gl\u00e4nzendes klebriges Sirupbutterbrot zum Fr\u00fchst\u00fcck! Welch sinnloses Charakteropfer! Unter den tastenden, spekulativ formenden H\u00e4nden des Erzeugers muss der Sinn f\u00fcr das Nahbare, das Verzeihbare, das Gef\u00e4llige verdorben sein. Der Erzeuger hat die Z\u00fcge dieses gemeinen Gesichtes zur Entfaltung und kurz vor einer ahnbaren N\u00e4he zu etwas Lebendigem in sofortige L\u00e4hmung, ja, Vereisung gezwungen. Gesicht \u00fcber dem Teller, Gesicht \u00fcber dem Abgrund, Gesicht im Fenster, Gesicht im Traum, Greisinnengesicht, Gesicht vor Gesicht, die Sinne linienverbunden, Gesicht des Jahrhunderts, Gesicht \u00fcber dem Panamakanal&#8230; Was hatte den Verursacher dieses Gesichtes bewegt, w\u00e4hrend unter seinen H\u00e4nden ein fades Entsetzen sich formte? Der pubertierend-weibliche Blick: wo endete er? Ich folgte der Richtung, und am Ende der Sackgasse rue du Tresor stand, was ich \u00e4ngstlich, ja, mit einem still noch gesteigerten Grauen erwartet hatte, das mich beherrscht hatte, seit ich -oder seit mich- die Puppe entdeckt hatte,: am Ende der Sackgasse stand ein alter, steinerne, beschmutzter und angeschlagener, verschlossener und somit toter Brunnen, wie abgestellt, \u00a0zu unattraktiv, um als historisch gelten zu k\u00f6nnen.<\/p>\n<p style=\"text-align: justify;\">Die Gemeinheit ist eine Scherbe, die, aus der gro\u00dfen Vase gebrochen, an den m\u00f6glichen Bruchstellen schon mit garantiert haftendem Leim bestrichen ist. So scheint jede verletzte Stelle heilbar. Angst schwitzt die angebrochene Kreatur immer aus, die nach einem Gegenst\u00fcck, dem passenden, um wieder ganz zu werden, verlangt. Vom schmucklosen Brunnen aus, zu dem mich der Puppenblick zwanghaft gef\u00fchrt hatte und vor dessen kraftloser Geschichtstr\u00e4chtigkeit ich mich dankbar in den Status einer Touristin f\u00fcgte, sah ich noch einmal zur\u00fcck. Jetzt stand eine junge Frau vor dem Schaufenster, presste ihr junges, unkontrolliertes Gesicht gegen die Scheibe, unsere Blicke begegneten und verlie\u00dfen einander sofort wieder. An ihrer Haltung konnte ich erkennen, dass sie g\u00e4nzlich fassungslos war. Ich wusste, dass sie drei Dinge zugleich im Blick hatte: mich, die Schaufensterpuppe, den Brunnen. Dann geschah etwas mit ihr.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Es vollzog sich eine Art Korrektur, nein, Reparatur an einem Insekt, das nach der Katastrophe \u00a0langsam im Harz erstarrt.\u00a0 Und ist es erst einmal ganz fest eingeschlossen, bleibt sein letzter Augenblick Jahrtausende sp\u00e4ter gl\u00fccklich eingesperrt f\u00fcr staunende Augen.<\/p>\n<p style=\"text-align: justify;\">\n<h4 style=\"text-align: justify;\"><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_19507\" style=\"width: 309px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2014\/02\/Angelika-Janz.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19507\" class=\"size-full wp-image-19507\" src=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2014\/02\/Angelika-Janz.jpg\" alt=\"\" width=\"299\" height=\"253\" \/><\/a><p id=\"caption-attachment-19507\" class=\"wp-caption-text\">Angelika Janz<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Weiterf\u00fchrend\u00a0\u2192\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">Lesen Sie auch das <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=36409\">Kollegengespr\u00e4ch<\/a>, das A.J. Weigoni mit Angelika Janz \u00fcber den Zyklus <em>fern, fern<\/em> gef\u00fchrt hat. Vertiefend ein <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=22835\">Portr\u00e4t <\/a>\u00fcber ihre interdisziplin\u00e4re T\u00e4tigkeit, sowie einen <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=29450\">Essay<\/a> der <em>Fragmenttexterin<\/em>. Ebenfalls im KUNO-Archiv: Jan Kuhlbrodt mit einer <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2012\/11\/05\/asthetische-prothetik\/\">Ann\u00e4herung<\/a> an die visuellen Arbeiten von Angelika Janz. Und nicht zuletzt, Michael Gratz \u00fcber Angelika Janz\u2018<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2012\/11\/05\/freiraum\/\"> tEXt bILd<\/a><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Rue Vieille du Temple, Paris. Kleine L\u00e4den, schmutzige Schaufensterscheiben. Dahinter verh\u00f6hnen seltsame Pr\u00e4sentationen den Abstand des Flaneurs zu den Gelassen stiller Rituale. Sie ziehen dich in Intimit\u00e4t, in vertrauliche Zusammenh\u00e4nge hinein, die man riechen kann. Alles Hingestellte, Ausgestellte, wirkt vorl\u00e4ufig,&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"http:\/\/www.editiondaslabor.de\/blog\/2003\/02\/02\/das-biografische-gesicht-unter-verschluss\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":53,"featured_media":98669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[918],"class_list":["post-104905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatur","tag-angelika-janz"],"_links":{"self":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/104905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/comments?post=104905"}],"version-history":[{"count":1,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/104905\/revisions"}],"predecessor-version":[{"id":104906,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/104905\/revisions\/104906"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media\/98669"}],"wp:attachment":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media?parent=104905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/categories?post=104905"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/tags?post=104905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}