{"id":102897,"date":"1995-09-15T00:57:00","date_gmt":"1995-09-14T22:57:00","guid":{"rendered":"http:\/\/www.editiondaslabor.de\/blog\/?p=102897"},"modified":"2022-04-26T14:05:02","modified_gmt":"2022-04-26T12:05:02","slug":"dichter-auf-dem-markt-der-persoenlichkeiten","status":"publish","type":"post","link":"http:\/\/www.editiondaslabor.de\/blog\/1995\/09\/15\/dichter-auf-dem-markt-der-persoenlichkeiten\/","title":{"rendered":"Dichter auf dem Markt der Pers\u00f6nlichkeiten"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Eine Bekanntheit, die nicht durch Medien, akademische Wissenschaft oder Kollegen aus der literarischen Nomenklatura legitimiert ist, zieht in der Regel die Abneigung der letzteren nach sich. Das Schaffen der Schriftsteller au\u00dferhalb des Mainstreams, das nicht mit dem \u00e4sthetischen Geschmack der Anerkannten und Anerkennenden \u00fcbereinstimmt, wird mit Begriffen wie \u00bbAnachronismus\u00ab, \u00bbBanalit\u00e4t\u00ab, \u00bbUnsinn\u00ab, \u00bbOutsidertum\u00ab usw. bewertet. (\u2026) Die Macher der Medienliteratur, die bestimmte literarische Gruppierungen bilden, welche in der Regel aus Stiftungsvorst\u00e4nden, Kritikern, gro\u00dfen Verlagen, Hochschulprofessoren, Jurymitgliedern diverser Wettbewerbe, Leitern von Literaturvereinen usw. bestehen, bestimmen die Verteilung finanzieller Mittel und reglementieren streng den Beitritt neuer Mitglieder nach einem Klan-Prinzip (bewerben sich, schreiben Kritiken, verlegen, verkaufen, vergeben Preise nach dem Grundsatz \u00bbwie ich dir \u2013 so du mir\u00ab) und blockieren des \u00f6fteren den neuen Anw\u00e4rtern den Zugang zu Verlagsm\u00f6glichkeiten, Preisen usw. Dieses Ph\u00e4nomen bekam bei den Teilnehmern des Literaturprozesses den Namen Literaturmafia. (\u2026) Man glaubt, da\u00df die Gruppe 47 einen gro\u00dfen Beitrag zur Entwicklung der Medienlandschaft geleistet hat. Wie K. M. Rarisch feststellt, hat eben in bezug auf sie der Schriftsteller R. Neumann in dem Magazin \u00bbkonkret\u00ab zum ersten Mal den Ausdruck \u00bbLiteraturmafia\u00ab benutzt. Rarisch verwendet diesen Begriff in zahlreichen Pressepolemiken sowie auch in literaturwissenschaftlichen Aufs\u00e4tzen. Die Vertreter der Literaturmafia sind seiner Meinung nach Figuren, deren Schaffen nach einer unausgesprochenen Abmachung keiner Kritik unterliegt: offizielle Kritik und Literaturwissenschaft wagen es nicht, gegen Autoren solchen Ranges aufzutreten. Rarisch selbst unterwirft einer h\u00f6hnischen Kritik die Gedichte von U. Kolbe, im besonderen in der Parodie auf dessen Gedicht \u00bbAusflug ohne Muse\u00ab; er f\u00fchrt Beispiele von Plagiaten an bei K. Krolow und G. Grass. (\u2026) Kritische Angriffe gegen bekannte Dichter, deren Werke nicht hochk\u00fcnstlerischen Kriterien entsprechen, wirken sich meistens nicht auf die Qualit\u00e4t ihrer nachfolgenden Gedichtb\u00e4nde aus und auf die Anzahl der Literaturpreise, die sie bekommen. So sieht U. Kolbes Gedicht \u00bbAusflug ohne Muse\u00ab, das vom Suhrkampverlag und von der Zeitung \u00bbTagesspiegel\u00ab beworben wurde, aus wie eine Selbstparodie auf die formale und inhaltliche Leere der postmodernistischen Transitweltempfindung. (\u2026) \u00bbAls Autor\u00ab (Rarisch schreibt haupts\u00e4chlich Sonette, und R. Wohlleben, nicht nur Verleger, sondern auch alter Freund und Kollege Rarischs, spezialisiert sich mit seinem Verlag genau auf dieses Genre \u2013 T. Kudrjawzewa) \u00bbbin ich f\u00fcr andere Verlage uninteressant. Das Manuskript eines meiner Gedichtb\u00e4nde schickte ich allen einschl\u00e4gigen Verlagen (\u00fcber 100); als Resultat bekam ich nur Absagen ohne Begr\u00fcndung bzw. mit der Bemerkung: Die Gedichte sind makellos in der Form, jedoch \u2026; oder es folgte \u00fcberhaupt keine Antwort \u2026\u00ab (\u2026) Es ist interessant zu bemerken: W\u00e4hrend Rarischs Gedichtband \u00bbDie Geigerz\u00e4hler h\u00f6ren auf zu ticken \u2013 99 Sonette mit einem Selbstkommentar\u00ab 1990 mit einer Auflage von 500 erschien, die bis heute nicht verkauft ist, erreichte der Band \u00bbNovemberland \u2013 13 Sonette\u00ab von G. Grass zwei Auflagen innerhalb eines Monats. 2003 wurde K. M. Rarisch auf Initiative der Zeitschrift \u00bbZirkular \u2013 am Zeitstrand\u00ab als Anw\u00e4rter f\u00fcr den prestigetr\u00e4chtigsten Literaturpreis in Deutschland vorgeschlagen, f\u00fcr den B\u00fcchnerpreis. Die Initiatoren dieser Kandidatur r\u00e4umen jedoch ein, da\u00df es eine hoffnungslose Sache sei (\u2026) Jedoch liegt es nicht nur an der Konventionalit\u00e4t der von Rarisch gew\u00e4hlten poetischen Form. Nicht zuletzt spielt beim Ignorieren der Werke des Dichters durch die Haie des Verlagsbusiness die inhaltliche Seite eine Rolle. Die sozialkritische Ausrichtung von Rarischs Sonetten (wie der Dichter selbst zugibt: \u00bbLinker als ich ist nur noch die Berliner Mauer\u00ab\u2026 harmoniert nicht mit der ideologisch faden Mainstreamproduktion, die das Bild des literarischen Marktes im modernen Deutschland bestimmt. (\u2026) Anla\u00df f\u00fcr Rarischs Sonett \u00bbBlutiger Zwischenfall\u00ab waren die Impressionen von der Preisverleihungsprozedur beim Ingeborg-Bachmann-Wettbewerb (\u2026) Beispielhaft ist die von K. M. Rarisch durchgef\u00fchrte Analyse der Rubrik \u00bbDas neue Gedicht\u00ab im Tagesspiegel in der Zeit vom 2. Juli bis 20. August 1995. Von acht Ver\u00f6ffentlichungen betreffen vier die Produktion des Suhrkampverlages. Auf der Literaturseite des Tagesspiegels Nr. 15363 vom 20.8.1995 sind drei von f\u00fcnf Kritiken den B\u00fcchern gewidmet, die in demselben Verlag erschienen sind. (\u2026) Typische Wesensz\u00fcge eines durchschnittlichen deutschen Kulturkonsumenten verk\u00f6rpert ein Leserbrief-Schreiber, ein Diplomingenieur. Nachdem er die gro\u00dfe Bedeutung der Poesie f\u00fcr das geistige Leben hervorgehoben und Goethe und Schiller unter seinen Lieblingsdichtern genannt hatte, erkl\u00e4rte er seinen fehlenden Drang zur Lekt\u00fcre von Gedichten mit Mangel an Freizeit.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p style=\"text-align: justify;\"><strong>Dichter auf dem Markt der Pers\u00f6nlichkeiten im gegenw\u00e4rtigen Deutschland<\/strong>, von Tamara Kudryavtseva<\/p>\n<div id=\"attachment_44595\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44595\" class=\"wp-image-44595 size-medium\" src=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2017\/09\/der-lyrik-eine-bresche-fuer-ein-gedicht-je-ausgabe-einer-zeitung_1505748323-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2017\/09\/der-lyrik-eine-bresche-fuer-ein-gedicht-je-ausgabe-einer-zeitung_1505748323-1-300x200.jpg 300w, http:\/\/www.editiondaslabor.de\/blog\/wp-content\/uploads\/2017\/09\/der-lyrik-eine-bresche-fuer-ein-gedicht-je-ausgabe-einer-zeitung_1505748323-1.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-44595\" class=\"wp-caption-text\">Poesie z\u00e4hlt f\u00fcr KUNO zu den identit\u00e4ts- und identifikationstiftenden Elementen der Kultur<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Weiterf\u00fchrend<\/strong> <strong>\u2192<\/strong> Poesie z\u00e4hlt f\u00fcr KUNO zu den identit\u00e4ts- und identifikationstiftenden Elementen der Kultur, dies bezeugt der Versuch einer <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=25630\">poetologischen Positionsbestimmung<\/a>. Um den Widerstand gegen die gepolsterte Gegenwartslyrik ein wenig anzufachen schickte <span data-offset-key=\"d96ve-1-0\">Wolfgang Schlott<\/span><span data-offset-key=\"d96ve-2-0\"> dieses\u00a0 post-dadaistische <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2016\/02\/03\/handwerkliche-anleitungen-zur-ueberwindung-von-schreibblockaden\/\">Manifest<\/a>. Warum<\/span> Lyrik wieder in die Zeitungen geh\u00f6rt <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/10\/07\/der-dichtung-eine-bresche-schlagen\/\">begr\u00fcndete<\/a> Walther Stonet, diese Forderung hat nichts an Aktualit\u00e4t verloren. Lesen Sie auch Maximilian Zanders <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=5418\">Essay <\/a>\u00fcber Lyrik und ein R\u00fcckblick auf den <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2014\/01\/08\/lyrik-katalog-bundesrepublik\/\"><em>Lyrik-Katalog Bundesrepublik<\/em><\/a>, sowie einen Essay \u00fcber den <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2013\/12\/26\/lauschender-leser-und-redender-schreiber-2\/\">Lyrikvermittler<\/a> Theo Breuer. KUNO sch\u00e4tzt den minuti\u00f6sen Selbstinszenierungsprozess des lyrischen Dichter-Ichs von Ulrich Bergmann in der Reihe <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=27947\">Keine Bojen auf hoher See, nur Sterne \u2026 und Schwerkraft. Gedanken \u00fcber das lyrische Schreiben<\/a>. Lesen Sie ein <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=22835\">Portr\u00e4t <\/a>\u00fcber die interdisziplin\u00e4re T\u00e4tigkeit von Angelika Janz, sowie einen <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=29450\">Essay<\/a> der <em>Fragmenttexterin.<\/em> Ein Portr\u00e4t von Sophie Reyer findet sich\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2013\/10\/08\/von-sappho-zu-sophie\/\">hier<\/a>, ein Essay fasst das transmediale Projekt<em> \u201e<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2021\/04\/14\/bi-textualitaet\/\">Wortspielhalle<\/a>\u201c <\/em>zusammen<em>. <\/em>Auf KUNO lesen Sie u.a. Rezensionsessays von <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2015\/06\/17\/beschwoerungszauber\/\">Holger Benkel<\/a> \u00fcber <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=15175\">Andr\u00e9 Schinkel<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/11\/12\/mit-deutschen-untertiteln\/\">Ralph Pordzik<\/a>,\u00a0<a href=\"http:\/\/www.editiondaslabor.de\/blog\/2018\/12\/20\/wohnraeume-der-poesie\/\">Friederike Mayr\u00f6cker<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/03\/19\/welten-gegenwelten\/\">Werner Weimar-Mazur<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2019\/06\/26\/wohnraeume-der-poesie-2\/\">Peter Engstler<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/?p=15177\">Birgitt Lieberwirth<\/a>, <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2019\/08\/17\/der-grill-auf-der-hauswiese-der-welt\/\">Linda Vilhj\u00e1lmsd\u00f3ttir<\/a>, und <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2017\/09\/17\/rettungsversuche-der-literatur-im-digitalen-raum\/\">A.J. Weigoni<\/a>. Lesenswert auch die <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2020\/05\/16\/verseschmied-und-lyrikfischer\/\">Gratulation<\/a> von Axel Kutsch durch Markus Peters zum 75. Geburtstag. Nicht zu vergessen eine Empfehlung der kristallklaren Lyrik von <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2020\/01\/19\/die-lyrikerin-ines-hagemeyer\/\">Ines Hagemeyer<\/a>. Diese Betrachtungen versammeln sich in der Tradition von <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2000\/04\/04\/vauo\/\">V.O. Stomps<\/a>, dem Klassiker des Andersseins, dem <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2005\/09\/24\/erinnerungen\/\">Bottroper Literaturrocker<\/a> &#8222;Biby&#8220; Wintjes und Hadayatullah H\u00fcbsch, dem Urvater des <a href=\"http:\/\/www.editiondaslabor.de\/blog\/1995\/06\/30\/wie-was-social-beat-ist-und-warum-und-warum-nicht\/\"><em>Social-Beat<\/em><\/a>, im KUNO-Online-Archiv. Wir empfehlen f\u00fcr Neulinge als Einstieg in das weite Feld der nonkonformistischen Literatur <a href=\"http:\/\/www.editiondaslabor.de\/blog\/2001\/04\/01\/nonkonformistische-literatur\/\">diesem Hinweis<\/a> zu folgen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Eine Bekanntheit, die nicht durch Medien, akademische Wissenschaft oder Kollegen aus der literarischen Nomenklatura legitimiert ist, zieht in der Regel die Abneigung der letzteren nach sich. Das Schaffen der Schriftsteller au\u00dferhalb des Mainstreams, das nicht mit dem \u00e4sthetischen Geschmack&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"http:\/\/www.editiondaslabor.de\/blog\/1995\/09\/15\/dichter-auf-dem-markt-der-persoenlichkeiten\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":127,"featured_media":98207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1477],"class_list":["post-102897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatur","tag-tamara-kudryavtseva"],"_links":{"self":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/102897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/comments?post=102897"}],"version-history":[{"count":3,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/102897\/revisions"}],"predecessor-version":[{"id":102900,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/posts\/102897\/revisions\/102900"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media\/98207"}],"wp:attachment":[{"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/media?parent=102897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/categories?post=102897"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.editiondaslabor.de\/blog\/wp-json\/wp\/v2\/tags?post=102897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}